{"id":6625,"date":"2019-07-11T13:45:28","date_gmt":"2019-07-11T11:45:28","guid":{"rendered":"http:\/\/maxims-caviar.com\/commande\/"},"modified":"2019-07-11T13:45:28","modified_gmt":"2019-07-11T11:45:28","slug":"commande","status":"publish","type":"page","link":"https:\/\/maxims-caviar.com\/en_fr\/commande\/","title":{"rendered":"Validation de la commande"},"content":{"rendered":"<div class=\"woocommerce\"><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6625","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Validation de la commande - Maxim&#039;s Caviar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maxims-caviar.com\/en_fr\/commande\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Validation de la commande - Maxim&#039;s Caviar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maxims-caviar.com\/en_fr\/commande\/\" \/>\n<meta property=\"og:site_name\" content=\"Maxim&#039;s Caviar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maxims-caviar.com\\\/commande\\\/\",\"url\":\"https:\\\/\\\/maxims-caviar.com\\\/commande\\\/\",\"name\":\"Validation de la commande - Maxim&#039;s Caviar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maxims-caviar.com\\\/en\\\/#website\"},\"datePublished\":\"2019-07-11T11:45:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maxims-caviar.com\\\/commande\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maxims-caviar.com\\\/commande\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maxims-caviar.com\\\/commande\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/maxims-caviar.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Validation de la commande\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maxims-caviar.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/maxims-caviar.com\\\/en\\\/\",\"name\":\"Maxim&#039;s Caviar\",\"description\":\"L&#039;alliance de l&#039;Histoire et de la Modernit\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/maxims-caviar.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maxims-caviar.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maxims-caviar.com\\\/en\\\/#organization\",\"name\":\"Maxim&#039;s Caviar\",\"url\":\"https:\\\/\\\/maxims-caviar.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maxims-caviar.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maxims-caviar.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/maxims-caviar.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/logo.png\",\"width\":470,\"height\":110,\"caption\":\"Maxim&#039;s Caviar\"},\"image\":{\"@id\":\"https:\\\/\\\/maxims-caviar.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Validation de la commande - Maxim&#039;s Caviar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maxims-caviar.com\/en_fr\/commande\/","og_locale":"en_US","og_type":"article","og_title":"Validation de la commande - Maxim&#039;s Caviar","og_url":"https:\/\/maxims-caviar.com\/en_fr\/commande\/","og_site_name":"Maxim&#039;s Caviar","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maxims-caviar.com\/commande\/","url":"https:\/\/maxims-caviar.com\/commande\/","name":"Validation de la commande - Maxim&#039;s Caviar","isPartOf":{"@id":"https:\/\/maxims-caviar.com\/en\/#website"},"datePublished":"2019-07-11T11:45:28+00:00","breadcrumb":{"@id":"https:\/\/maxims-caviar.com\/commande\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maxims-caviar.com\/commande\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/maxims-caviar.com\/commande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/maxims-caviar.com\/"},{"@type":"ListItem","position":2,"name":"Validation de la commande"}]},{"@type":"WebSite","@id":"https:\/\/maxims-caviar.com\/en\/#website","url":"https:\/\/maxims-caviar.com\/en\/","name":"Maxim&#039;s Caviar","description":"L&#039;alliance de l&#039;Histoire et de la Modernit\u00e9","publisher":{"@id":"https:\/\/maxims-caviar.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maxims-caviar.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/maxims-caviar.com\/en\/#organization","name":"Maxim&#039;s Caviar","url":"https:\/\/maxims-caviar.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maxims-caviar.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/maxims-caviar.com\/wp-content\/uploads\/2019\/07\/logo.png","contentUrl":"https:\/\/maxims-caviar.com\/wp-content\/uploads\/2019\/07\/logo.png","width":470,"height":110,"caption":"Maxim&#039;s Caviar"},"image":{"@id":"https:\/\/maxims-caviar.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/maxims-caviar.com\/en_fr\/wp-json\/wp\/v2\/pages\/6625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maxims-caviar.com\/en_fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maxims-caviar.com\/en_fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maxims-caviar.com\/en_fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maxims-caviar.com\/en_fr\/wp-json\/wp\/v2\/comments?post=6625"}],"version-history":[{"count":0,"href":"https:\/\/maxims-caviar.com\/en_fr\/wp-json\/wp\/v2\/pages\/6625\/revisions"}],"wp:attachment":[{"href":"https:\/\/maxims-caviar.com\/en_fr\/wp-json\/wp\/v2\/media?parent=6625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}